{"id":1538,"date":"2010-07-14T00:00:00","date_gmt":"2010-07-14T03:00:00","guid":{"rendered":"http:\/\/ajupe.com.uy\/web\/?post_type=product&#038;p=1538"},"modified":"2010-07-14T00:00:00","modified_gmt":"2010-07-14T03:00:00","slug":"el-secreto-de-monna-lisa","status":"publish","type":"product","link":"https:\/\/ajupe.com.uy\/web\/biblioteca\/el-secreto-de-monna-lisa\/","title":{"rendered":"El secreto de Monna Lisa"},"content":{"rendered":"<p>En su primera novela, Dolores Garc\u00eda consigue acercarnos a lo que podr\u00eda haber sido el lado desconocido del genio florentino Leonardo Da Vinci. A trav\u00e9s de su narrador (Francisco Melzi) asistimos a las \u00faltimas horas de Leonardo, en la corte del rey franc\u00e9s Francisco I. Melzi, intrigado por la raz\u00f3n por la que el maestro est\u00e1 obsesionado con su obra La Gioconda, la \u00fanica que le ha acompa\u00f1ado en todos sus viajes, le pide que le explique su historia. Da Vinci empezar\u00e1 entonces el fascinante relato de su vida, desde el momento en que se ve obligado a huir de Mil\u00e1n tras la ca\u00edda del poder de Ludovico I.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su primera novela, Dolores Garc\u00eda consigue acercarnos a lo que podr\u00eda haber sido el lado desconocido del genio florentino Leonardo Da Vinci. A trav\u00e9s de su narrador (Francisco Melzi) asistimos a las \u00faltimas horas de Leonardo, en la corte del rey franc\u00e9<\/p>\n","protected":false},"featured_media":1539,"template":"","meta":[],"product_brand":[436],"product_cat":[30],"product_tag":[],"class_list":["post-1538","product","type-product","status-publish","has-post-thumbnail","product_brand-dolores-garcia","product_cat-suspenso","first","instock","purchasable","product-type-simple"],"featured_image_urls_v2":{"full":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849.jpg",360,549,false],"thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849.jpg",150,150,true],"medium":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849.jpg",300,214,true],"medium_large":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849.jpg",360,549,false],"large":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849.jpg",360,549,false],"1536x1536":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849.jpg",360,549,false],"2048x2048":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849.jpg",360,549,false],"woocommerce_archive_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849-300x450.jpg",300,450,true],"woocommerce_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849-300x458.jpg",300,458,true],"woocommerce_gallery_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-1538-6849-100x100.jpg",100,100,true]},"post_excerpt_stackable_v2":"<p>En su primera novela, Dolores Garc\u00eda consigue acercarnos a lo que podr\u00eda haber sido el lado desconocido del genio florentino Leonardo Da Vinci. A trav\u00e9s de su narrador (Francisco Melzi) asistimos a las \u00faltimas horas de Leonardo, en la corte del rey franc\u00e9<\/p>\n","category_list_v2":"","author_info_v2":{"name":"","url":""},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product\/1538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/media\/1539"}],"wp:attachment":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/media?parent=1538"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_brand?post=1538"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_cat?post=1538"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_tag?post=1538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}