{"id":2140,"date":"2010-07-14T00:00:00","date_gmt":"2010-07-14T03:00:00","guid":{"rendered":"http:\/\/ajupe.com.uy\/web\/?post_type=product&#038;p=2140"},"modified":"2011-09-16T22:21:25","modified_gmt":"2011-09-17T01:21:25","slug":"las-torres-del-olvido","status":"publish","type":"product","link":"https:\/\/ajupe.com.uy\/web\/biblioteca\/las-torres-del-olvido\/","title":{"rendered":"Las Torres Del Olvido"},"content":{"rendered":"<p>Australia, una serie de torres gigantescas se elevan medio en ruinas sobre las aguas de la bah\u00eda de Melbourne. Son el \u00faltimo vestigio de una civilizaci\u00f3n autodestruida a mediados del siglo xxi: rascacielos fantasmales comidos por los siglos y casi sumergidos en el mar a causa del efecto invernadero. Una joven historiadora, empe\u00f1ada en reconstruir la vida de aquella \u00e9poca de convulsiones sociales, superpoblaci\u00f3n y trastornos clim\u00e1ticos, decide dar a sus conclusiones la forma de una novela. En los personajes que imagina -los antiguos habitantes de las torres- redescubre un mundo degradado por la codicia y la indiferencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Australia, una serie de torres gigantescas se elevan medio en ruinas sobre las aguas de la bah\u00eda de Melbourne. Son el \u00faltimo vestigio de una civilizaci\u00f3n autodestruida a mediados del siglo xxi: rascacielos fantasmales comidos por los siglos y casi sumergi<\/p>\n","protected":false},"featured_media":2141,"template":"","meta":[],"product_brand":[666],"product_cat":[29],"product_tag":[],"class_list":["post-2140","product","type-product","status-publish","has-post-thumbnail","product_brand-george-turner","product_cat-novela","first","instock","purchasable","product-type-simple"],"featured_image_urls_v2":{"full":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474.jpg",248,390,false],"thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474.jpg",150,150,true],"medium":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474.jpg",300,214,true],"medium_large":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474.jpg",248,390,false],"large":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474.jpg",248,390,false],"1536x1536":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474.jpg",248,390,false],"2048x2048":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474.jpg",248,390,false],"woocommerce_archive_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474-248x300.jpg",248,300,true],"woocommerce_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474-248x300.jpg",248,300,true],"woocommerce_single":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474.jpg",248,390,false],"woocommerce_gallery_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-2140-7474-100x100.jpg",100,100,true]},"post_excerpt_stackable_v2":"<p>Australia, una serie de torres gigantescas se elevan medio en ruinas sobre las aguas de la bah\u00eda de Melbourne. Son el \u00faltimo vestigio de una civilizaci\u00f3n autodestruida a mediados del siglo xxi: rascacielos fantasmales comidos por los siglos y casi sumergi<\/p>\n","category_list_v2":"","author_info_v2":{"name":"","url":""},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product\/2140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/media\/2141"}],"wp:attachment":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/media?parent=2140"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_brand?post=2140"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_cat?post=2140"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_tag?post=2140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}