{"id":3800,"date":"2011-09-27T19:09:34","date_gmt":"2011-09-27T22:09:34","guid":{"rendered":"http:\/\/ajupe.com.uy\/web\/?post_type=product&#038;p=3800"},"modified":"2011-09-28T19:27:18","modified_gmt":"2011-09-28T22:27:18","slug":"pura-venganza","status":"publish","type":"product","link":"https:\/\/ajupe.com.uy\/web\/biblioteca\/pura-venganza\/","title":{"rendered":"Pura venganza"},"content":{"rendered":"<p><span id=\"ctl00_ContentPlaceHolder1_lblResena\">En 1943, Marcellus  Prandus era un capit\u00e1n de la milicia lituana a las \u00f3rdenes de los nazis   durante la Segunda Guerra Mundial. Hoy es un hombre viejo que ha  escapado a todo castigo y vive tranquilamente en Boston rodeado de su  familia. Para Max, que descubri\u00f3 la identidad del asesino de manera  casual, matarlo no es suficiente.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1943, Marcellus Prandus era un capit\u00e1n de la milicia lituana a las \u00f3rdenes de los nazis durante la Segunda Guerra Mundial. Hoy es un hombre viejo que ha escapado a todo castigo y vive tranquilamente en Boston rodeado de su familia. Para Max, que descubri\u00f3 la identidad del asesino de manera casual, matarlo no [&hellip;]<\/p>\n","protected":false},"featured_media":3801,"template":"","meta":[],"product_brand":[536],"product_cat":[30],"product_tag":[],"class_list":["post-3800","product","type-product","status-publish","has-post-thumbnail","product_brand-alan-m-dershowitz","product_cat-suspenso","first","instock","purchasable","product-type-simple"],"featured_image_urls_v2":{"full":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed.jpg",338,500,false],"thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed.jpg",150,150,true],"medium":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed.jpg",300,214,true],"medium_large":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed.jpg",338,500,false],"large":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed.jpg",338,500,false],"1536x1536":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed.jpg",338,500,false],"2048x2048":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed.jpg",338,500,false],"woocommerce_archive_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed-300x450.jpg",300,450,true],"woocommerce_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed-300x444.jpg",300,444,true],"woocommerce_gallery_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/04\/p-3800-Pura_venganzaa_4e821f6eba6ed-100x100.jpg",100,100,true]},"post_excerpt_stackable_v2":"<p>En 1943, Marcellus Prandus era un capit\u00e1n de la milicia lituana a las \u00f3rdenes de los nazis durante la Segunda Guerra Mundial. Hoy es un hombre viejo que ha escapado a todo castigo y vive tranquilamente en Boston rodeado de su familia. Para Max, que descubri\u00f3 la identidad del asesino de manera casual, matarlo no es suficiente.<\/p>\n","category_list_v2":"","author_info_v2":{"name":"","url":""},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product\/3800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/media\/3801"}],"wp:attachment":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/media?parent=3800"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_brand?post=3800"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_cat?post=3800"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_tag?post=3800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}