{"id":8359,"date":"2016-06-22T17:25:44","date_gmt":"2016-06-22T20:25:44","guid":{"rendered":"http:\/\/ajupe.com.uy\/web\/producto\/las-raices-del-mal-2\/"},"modified":"2016-06-22T17:27:36","modified_gmt":"2016-06-22T20:27:36","slug":"las-raices-del-mal-2","status":"publish","type":"product","link":"https:\/\/ajupe.com.uy\/web\/biblioteca\/las-raices-del-mal-2\/","title":{"rendered":"Las ra\u00edces del mal"},"content":{"rendered":"<p>Gardiner, la prometida de un rico heredero, es la principal sospechosa del asesinato del conductor del carromato en que viajaba. Resulta dif\u00edcil entender por qu\u00e9 una joven con un brillante futuro cometer\u00eda un acto similar. El enigma desembocar\u00e1 en los tribunales, donde el abogado O. Rathbone, asesorado por W. Monk y su esposa Hester, deber\u00e1 invertir toda su sagacidad para defender a una mujer que est\u00e1 dispuesta a aceptar la horca antes que desvelar un secreto del pasado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gardiner, la prometida de un rico heredero, es la principal sospechosa del asesinato del conductor del carromato en que viajaba. Resulta dif\u00edcil entender por qu\u00e9 una joven con un brillante futuro cometer\u00eda un acto similar. El enigma desembocar\u00e1 en los tribunales, donde el abogado O. Rathbone, asesorado por W. Monk y su esposa Hester, deber\u00e1 [&hellip;]<\/p>\n","protected":false},"featured_media":8255,"template":"","meta":[],"product_brand":[],"product_cat":[30],"product_tag":[],"class_list":["post-8359","product","type-product","status-publish","has-post-thumbnail","product_cat-suspenso","first","instock","purchasable","product-type-simple"],"featured_image_urls_v2":{"full":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929.jpg",219,337,false],"thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929-150x150.jpg",150,150,true],"medium":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929-195x300.jpg",195,300,true],"medium_large":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929.jpg",219,337,false],"large":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929.jpg",219,337,false],"1536x1536":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929.jpg",219,337,false],"2048x2048":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929.jpg",219,337,false],"woocommerce_archive_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929-219x300.jpg",219,300,true],"woocommerce_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929-219x300.jpg",219,300,true],"woocommerce_single":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929.jpg",219,337,false],"woocommerce_gallery_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2016\/06\/8929-100x100.jpg",100,100,true]},"post_excerpt_stackable_v2":"<p>Gardiner, la prometida de un rico heredero, es la principal sospechosa del asesinato del conductor del carromato en que viajaba. Resulta dif\u00edcil entender por qu\u00e9 una joven con un brillante futuro cometer\u00eda un acto similar. El enigma desembocar\u00e1 en los tribunales, donde el abogado O. Rathbone, asesorado por W. Monk y su esposa Hester, deber\u00e1 invertir toda su sagacidad para defender a una mujer que est\u00e1 dispuesta a aceptar la horca antes que desvelar un secreto del pasado.<\/p>\n","category_list_v2":"","author_info_v2":{"name":"","url":""},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product\/8359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/media\/8255"}],"wp:attachment":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/media?parent=8359"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_brand?post=8359"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_cat?post=8359"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_tag?post=8359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}