{"id":8973,"date":"2017-02-24T15:01:36","date_gmt":"2017-02-24T18:01:36","guid":{"rendered":"http:\/\/ajupe.com.uy\/web\/producto\/el-caballo-de-cesar-2\/"},"modified":"2017-02-24T15:09:32","modified_gmt":"2017-02-24T18:09:32","slug":"el-caballo-de-cesar-2","status":"publish","type":"product","link":"https:\/\/ajupe.com.uy\/web\/biblioteca\/el-caballo-de-cesar-2\/","title":{"rendered":"El caballo de Cesar"},"content":{"rendered":"<p>En el apogeo de su carrera, Julio C\u00e9sar ha sometido a sus enemigos y ha ensanchado el imperio hasta los confines del mundo conocido. Muchos de los que le rodean consideran sus atribuciones de dictador como una amenaza para la Rep\u00fablica. Entre ellos, el lujurioso Marco Antonio, el resentido Cayo Casio o el virtuoso Marco Bruto. Sin heredero leg\u00edtimo, Julio C\u00e9sar, cuyo \u00fanico hijo es fruto de su uni\u00f3n con Cleopatra, ver\u00e1 en el joven Octavio a su posible sucesor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el apogeo de su carrera, Julio C\u00e9sar ha sometido a sus enemigos y ha ensanchado el imperio hasta los confines del mundo conocido. Muchos de los que le rodean consideran sus atribuciones de dictador como una amenaza para la Rep\u00fablica. Entre ellos, el lujurioso Marco Antonio, el resentido Cayo Casio o el virtuoso Marco [&hellip;]<\/p>\n","protected":false},"featured_media":8959,"template":"","meta":[],"product_brand":[],"product_cat":[31,29],"product_tag":[],"class_list":["post-8973","product","type-product","status-publish","has-post-thumbnail","product_cat-historico","product_cat-novela","first","instock","purchasable","product-type-simple"],"featured_image_urls_v2":{"full":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055.jpg",199,300,false],"thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055-150x150.jpg",150,150,true],"medium":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055-199x300.jpg",199,300,true],"medium_large":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055.jpg",199,300,false],"large":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055.jpg",199,300,false],"1536x1536":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055.jpg",199,300,false],"2048x2048":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055.jpg",199,300,false],"woocommerce_archive_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055.jpg",199,300,false],"woocommerce_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055.jpg",199,300,false],"woocommerce_single":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055.jpg",199,300,false],"woocommerce_gallery_thumbnail":["https:\/\/ajupe.com.uy\/web\/wp-content\/uploads\/2017\/02\/9055-100x100.jpg",100,100,true]},"post_excerpt_stackable_v2":"<p>En el apogeo de su carrera, Julio C\u00e9sar ha sometido a sus enemigos y ha ensanchado el imperio hasta los confines del mundo conocido. Muchos de los que le rodean consideran sus atribuciones de dictador como una amenaza para la Rep\u00fablica. Entre ellos, el lujurioso Marco Antonio, el resentido Cayo Casio o el virtuoso Marco Bruto. Sin heredero leg\u00edtimo, Julio C\u00e9sar, cuyo \u00fanico hijo es fruto de su uni\u00f3n con Cleopatra, ver\u00e1 en el joven Octavio a su posible sucesor.<\/p>\n","category_list_v2":"","author_info_v2":{"name":"","url":""},"comments_num_v2":"0 comentarios","_links":{"self":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product\/8973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/media\/8959"}],"wp:attachment":[{"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/media?parent=8973"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_brand?post=8973"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_cat?post=8973"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ajupe.com.uy\/web\/wp-json\/wp\/v2\/product_tag?post=8973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}